{"id":69,"date":"2022-05-15T12:01:14","date_gmt":"2022-05-15T12:01:14","guid":{"rendered":"https:\/\/coralive.org\/?p=69"},"modified":"2024-08-24T09:42:52","modified_gmt":"2024-08-24T08:42:52","slug":"updates-from-our-coral-research-in-theseychelles","status":"publish","type":"post","link":"https:\/\/www.coralive.org\/fr\/updates-from-our-coral-research-in-theseychelles\/","title":{"rendered":"Mise \u00e0 jour de nos recherches sur le corail aux Seychelles"},"content":{"rendered":"<p class=\"wp-block-paragraph\">15 mai 2022<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Apr\u00e8s des mois de travail m\u00e9ticuleux sur l'\u00eele de Fregate, aux Seychelles, notre exp\u00e9rience de restauration corallienne d'une dur\u00e9e d'un an touche \u00e0 sa fin. En nous associant \u00e0 Blancpain Ocean Commitment pour ce projet, nous savions que la technologie d'accr\u00e9tion min\u00e9rale (MAT) favoriserait la croissance, la sant\u00e9 et la survie des fragments de coraux transplant\u00e9s. Notre principal objectif \u00e9tait d'optimiser cette technologie pour la rendre plus efficace et plus durable. Cette exp\u00e9rience, men\u00e9e par notre biologiste marine Julie Pezin, a pris en compte quatre esp\u00e8ces diff\u00e9rentes de coraux, trois cycles de dur\u00e9e d'\u00e9lectrification et un nettoyage d'entretien, dans l'id\u00e9e d'\u00e9tablir des lignes directrices pour les futurs projets de restauration de coraux \u00e0 grande \u00e9chelle.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Apr\u00e8s un an, nos r\u00e9sultats indiquent que le MAT a eu un effet positif sur la fixation et la survie des fragments de coraux, avec 97% de fragments vivants sur les structures \u00e9lectrifi\u00e9es, contre 90% sur les structures non \u00e9lectrifi\u00e9es, ce qui indique que, outre les effets positifs du MAT, notre projet de restauration corallienne a \u00e9t\u00e9 un succ\u00e8s global.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ici, sur l'\u00eele de Fregate, le nettoyage des structures des tables n'a pas eu d'effet b\u00e9n\u00e9fique sur la croissance corallienne, ce qui peut s'expliquer par le faible encrassement par les algues sur ce site sp\u00e9cifique. Cela signifie que le nettoyage peut \u00eatre r\u00e9duit, voire supprim\u00e9, sans effets n\u00e9fastes sur la croissance corallienne, tout en \u00e9conomisant les ressources et le temps total pass\u00e9 sous l'eau.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La MAT a \u00e9t\u00e9 b\u00e9n\u00e9fique \u00e0 la croissance de certaines esp\u00e8ces plus que d'autres, mais dans l'ensemble, les taux de croissance les plus \u00e9lev\u00e9s ont \u00e9t\u00e9 obtenus avec 12 heures d'\u00e9lectrification pendant la nuit.  Cela sugg\u00e8re que nous pouvons soutenir efficacement la croissance des coraux transplant\u00e9s en utilisant seulement la moiti\u00e9 de l'\u00e9lectricit\u00e9 n\u00e9cessaire.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De plus, un total de 81 nouvelles colonies, dont 94% sont des Pocillopora meandrina, se sont naturellement \u00e9tablies sur les structures exp\u00e9rimentales. Ces nouvelles colonies avaient une nette pr\u00e9f\u00e9rence pour les structures non \u00e9lectrifi\u00e9es. Toutefois, compte tenu des \u00e9tudes pr\u00e9c\u00e9dentes, nous pensons que le substrat cr\u00e9\u00e9 par les MAT sera plus appropri\u00e9 que les structures non \u00e9lectrifi\u00e9es une fois que l'\u00e9lectricit\u00e9 sera coup\u00e9e.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En outre, depuis le d\u00e9but de l'exp\u00e9rience, nous avons observ\u00e9 une augmentation globale de l'abondance des poissons et plus encore de leur diversit\u00e9, ce qui montre qu'en augmentant la complexit\u00e9 structurelle d'un site de r\u00e9cif corallien d\u00e9grad\u00e9, nous avons fourni l'habitat stable n\u00e9cessaire aux esp\u00e8ces de poissons environnantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ces r\u00e9sultats sugg\u00e8rent que, m\u00eame si le MAT pr\u00e9sente des avantages \u00e9vidents pour l'attachement des fragments coralliens et la survie ult\u00e9rieure, la programmation de l'\u00e9lectrification et du nettoyage d'entretien peut \u00eatre optimis\u00e9e pour une meilleure croissance et un meilleur recrutement des coraux.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quelles sont les prochaines \u00e9tapes ? Nous pr\u00e9voyons d'\u00e9lectrifier toutes les structures de tables (y compris celles qui ne le sont pas) 12 heures par nuit et de multiplier par trois la taille de la p\u00e9pini\u00e8re. Les structures de tables enti\u00e8rement envahies par la v\u00e9g\u00e9tation seront d\u00e9plac\u00e9es vers des zones d\u00e9grad\u00e9es pour des interventions de restauration rapides. Ce faisant, nous fournirons un substrat appropri\u00e9 pour l'\u00e9tablissement de nouvelles colonies, tout en augmentant l'efficacit\u00e9 de l'effort de transplantation.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Enfin, une \u00e9valuation plus approfondie des avantages des MAT sera r\u00e9alis\u00e9e dans les mois \u00e0 venir, afin de comprendre comment nous pouvons combiner diff\u00e9rentes approches de restauration \u00e0 des fins d'apprentissage, mais aussi pour offrir les meilleurs avantages \u00e0 toutes les esp\u00e8ces de coraux.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous pr\u00e9senterons \u00e9galement les r\u00e9sultats et un poster lors du symposium international sur les r\u00e9cifs coralliens qui se tiendra \u00e0 Br\u00eame du 3 au 8 juillet.<\/p>","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s des mois de travail m\u00e9ticuleux sur l'\u00eele de Fregate, aux Seychelles, notre exp\u00e9rience de restauration corallienne d'une dur\u00e9e d'un an touche \u00e0 sa fin. En nous associant \u00e0 Blancpain Ocean Commitment pour ce projet, nous savions que la technologie d'accr\u00e9tion min\u00e9rale (MAT) favoriserait la croissance, la sant\u00e9 et la survie des fragments de coraux transplant\u00e9s.<\/p>","protected":false},"author":1,"featured_media":63,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-69","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"After months of meticulous work on Fregate Island, Seychelles, our 1 year-long coral restoration experiment comes to an end. Partnering on this project with Blancpain Ocean Commitment, we knew that Mineral Accretion Technology (MAT) would support the growth, health and survival of transplanted coral fragments.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Coralive\"\/>\n\t<meta name=\"google-site-verification\" content=\"ogykNNKnZk4x-OCXz5ErZU1TwjAk3MWUNK_CKSsfDRU\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.coralive.org\/fr\/updates-from-our-coral-research-in-theseychelles\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Coralive - Powering the Future of Coral Restoration.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Updates from our Coral Research in the Seychelles - Coralive\" \/>\n\t\t<meta property=\"og:description\" content=\"After months of meticulous work on Fregate Island, Seychelles, our 1 year-long coral restoration experiment comes to an end. Partnering on this project with Blancpain Ocean Commitment, we knew that Mineral Accretion Technology (MAT) would support the growth, health and survival of transplanted coral fragments.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.coralive.org\/fr\/updates-from-our-coral-research-in-theseychelles\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-05-15T12:01:14+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-08-24T08:42:52+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/coral.alive\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Updates from our Coral Research in the Seychelles - Coralive\" \/>\n\t\t<meta name=\"twitter:description\" content=\"After months of meticulous work on Fregate Island, Seychelles, our 1 year-long coral restoration experiment comes to an end. Partnering on this project with Blancpain Ocean Commitment, we knew that Mineral Accretion Technology (MAT) would support the growth, health and survival of transplanted coral fragments.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.coralive.org\\\/fr\\\/updates-from-our-coral-research-in-theseychelles\\\/#blogposting\",\"name\":\"Updates from our Coral Research in the Seychelles - Coralive\",\"headline\":\"Updates from our Coral Research in the Seychelles\",\"author\":{\"@id\":\"https:\\\/\\\/www.coralive.org\\\/fr\\\/author\\\/rosybrown-swan-745870-hostingersite-com\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.coralive.org\\\/fr\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.coralive.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/coral-research-in-the-seychelles-scaled.jpg\",\"width\":2560,\"height\":1920},\"datePublished\":\"2022-05-15T12:01:14+01:00\",\"dateModified\":\"2024-08-24T09:42:52+01:00\",\"inLanguage\":\"fr-FR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.coralive.org\\\/fr\\\/updates-from-our-coral-research-in-theseychelles\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.coralive.org\\\/fr\\\/updates-from-our-coral-research-in-theseychelles\\\/#webpage\"},\"articleSection\":\"Blog\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.coralive.org\\\/fr\\\/updates-from-our-coral-research-in-theseychelles\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.coralive.org\\\/fr#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.coralive.org\\\/fr\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.coralive.org\\\/fr\\\/category\\\/blog\\\/#listItem\",\"name\":\"Blog\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.coralive.org\\\/fr\\\/category\\\/blog\\\/#listItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.coralive.org\\\/fr\\\/category\\\/blog\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.coralive.org\\\/fr\\\/updates-from-our-coral-research-in-theseychelles\\\/#listItem\",\"name\":\"Updates from our Coral Research in the Seychelles\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.coralive.org\\\/fr#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.coralive.org\\\/fr\\\/updates-from-our-coral-research-in-theseychelles\\\/#listItem\",\"position\":3,\"name\":\"Updates from our Coral Research in the Seychelles\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.coralive.org\\\/fr\\\/category\\\/blog\\\/#listItem\",\"name\":\"Blog\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.coralive.org\\\/fr\\\/#organization\",\"name\":\"Coralive\",\"description\":\"Powering the Future of Coral Restoration. Powering the future of coral restoration Powering the Future of Coral Restoration. Protect what is important. Restore what is needed.\",\"url\":\"https:\\\/\\\/www.coralive.org\\\/fr\\\/\",\"telephone\":\"+41445868663\",\"foundingDate\":\"2016-07-01\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.coralive.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/horizontal-white.png\",\"@id\":\"https:\\\/\\\/www.coralive.org\\\/fr\\\/updates-from-our-coral-research-in-theseychelles\\\/#organizationLogo\",\"width\":199,\"height\":42},\"image\":{\"@id\":\"https:\\\/\\\/www.coralive.org\\\/fr\\\/updates-from-our-coral-research-in-theseychelles\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/coral.alive\",\"https:\\\/\\\/instagram.com\\\/coral.alive\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC0M62c864PkjbnLQ8JIYdVw\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/coralive-org\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.coralive.org\\\/fr\\\/author\\\/rosybrown-swan-745870-hostingersite-com\\\/#author\",\"url\":\"https:\\\/\\\/www.coralive.org\\\/fr\\\/author\\\/rosybrown-swan-745870-hostingersite-com\\\/\",\"name\":\"Coralive\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.coralive.org\\\/fr\\\/updates-from-our-coral-research-in-theseychelles\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6049c3d2ab23d730f1e9596931521d53e01945291f18c51f95f6af1c9ef8621b?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Coralive\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.coralive.org\\\/fr\\\/updates-from-our-coral-research-in-theseychelles\\\/#webpage\",\"url\":\"https:\\\/\\\/www.coralive.org\\\/fr\\\/updates-from-our-coral-research-in-theseychelles\\\/\",\"name\":\"Updates from our Coral Research in the Seychelles - Coralive\",\"description\":\"After months of meticulous work on Fregate Island, Seychelles, our 1 year-long coral restoration experiment comes to an end. Partnering on this project with Blancpain Ocean Commitment, we knew that Mineral Accretion Technology (MAT) would support the growth, health and survival of transplanted coral fragments.\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.coralive.org\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.coralive.org\\\/fr\\\/updates-from-our-coral-research-in-theseychelles\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.coralive.org\\\/fr\\\/author\\\/rosybrown-swan-745870-hostingersite-com\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.coralive.org\\\/fr\\\/author\\\/rosybrown-swan-745870-hostingersite-com\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.coralive.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/coral-research-in-the-seychelles-scaled.jpg\",\"@id\":\"https:\\\/\\\/www.coralive.org\\\/fr\\\/updates-from-our-coral-research-in-theseychelles\\\/#mainImage\",\"width\":2560,\"height\":1920},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.coralive.org\\\/fr\\\/updates-from-our-coral-research-in-theseychelles\\\/#mainImage\"},\"datePublished\":\"2022-05-15T12:01:14+01:00\",\"dateModified\":\"2024-08-24T09:42:52+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.coralive.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.coralive.org\\\/fr\\\/\",\"name\":\"Coralive\",\"description\":\"Powering the Future of Coral Restoration.\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.coralive.org\\\/fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Updates from our Coral Research in the Seychelles - Coralive","description":"Apr\u00e8s des mois de travail m\u00e9ticuleux sur l'\u00eele de Fregate, aux Seychelles, notre exp\u00e9rience de restauration corallienne d'une dur\u00e9e d'un an touche \u00e0 sa fin. En nous associant \u00e0 Blancpain Ocean Commitment pour ce projet, nous savions que la technologie d'accr\u00e9tion min\u00e9rale (MAT) favoriserait la croissance, la sant\u00e9 et la survie des fragments de coraux transplant\u00e9s.","canonical_url":"https:\/\/www.coralive.org\/fr\/updates-from-our-coral-research-in-theseychelles\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"ogykNNKnZk4x-OCXz5ErZU1TwjAk3MWUNK_CKSsfDRU","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.coralive.org\/fr\/updates-from-our-coral-research-in-theseychelles\/#blogposting","name":"Updates from our Coral Research in the Seychelles - Coralive","headline":"Updates from our Coral Research in the Seychelles","author":{"@id":"https:\/\/www.coralive.org\/fr\/author\/rosybrown-swan-745870-hostingersite-com\/#author"},"publisher":{"@id":"https:\/\/www.coralive.org\/fr\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.coralive.org\/wp-content\/uploads\/2024\/05\/coral-research-in-the-seychelles-scaled.jpg","width":2560,"height":1920},"datePublished":"2022-05-15T12:01:14+01:00","dateModified":"2024-08-24T09:42:52+01:00","inLanguage":"fr-FR","mainEntityOfPage":{"@id":"https:\/\/www.coralive.org\/fr\/updates-from-our-coral-research-in-theseychelles\/#webpage"},"isPartOf":{"@id":"https:\/\/www.coralive.org\/fr\/updates-from-our-coral-research-in-theseychelles\/#webpage"},"articleSection":"Blog"},{"@type":"BreadcrumbList","@id":"https:\/\/www.coralive.org\/fr\/updates-from-our-coral-research-in-theseychelles\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.coralive.org\/fr#listItem","position":1,"name":"Home","item":"https:\/\/www.coralive.org\/fr","nextItem":{"@type":"ListItem","@id":"https:\/\/www.coralive.org\/fr\/category\/blog\/#listItem","name":"Blog"}},{"@type":"ListItem","@id":"https:\/\/www.coralive.org\/fr\/category\/blog\/#listItem","position":2,"name":"Blog","item":"https:\/\/www.coralive.org\/fr\/category\/blog\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.coralive.org\/fr\/updates-from-our-coral-research-in-theseychelles\/#listItem","name":"Updates from our Coral Research in the Seychelles"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.coralive.org\/fr#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.coralive.org\/fr\/updates-from-our-coral-research-in-theseychelles\/#listItem","position":3,"name":"Updates from our Coral Research in the Seychelles","previousItem":{"@type":"ListItem","@id":"https:\/\/www.coralive.org\/fr\/category\/blog\/#listItem","name":"Blog"}}]},{"@type":"Organization","@id":"https:\/\/www.coralive.org\/fr\/#organization","name":"Coralive","description":"Powering the Future of Coral Restoration. Powering the future of coral restoration Powering the Future of Coral Restoration. Protect what is important. Restore what is needed.","url":"https:\/\/www.coralive.org\/fr\/","telephone":"+41445868663","foundingDate":"2016-07-01","logo":{"@type":"ImageObject","url":"https:\/\/www.coralive.org\/wp-content\/uploads\/2024\/05\/horizontal-white.png","@id":"https:\/\/www.coralive.org\/fr\/updates-from-our-coral-research-in-theseychelles\/#organizationLogo","width":199,"height":42},"image":{"@id":"https:\/\/www.coralive.org\/fr\/updates-from-our-coral-research-in-theseychelles\/#organizationLogo"},"sameAs":["https:\/\/facebook.com\/coral.alive","https:\/\/instagram.com\/coral.alive","https:\/\/www.youtube.com\/channel\/UC0M62c864PkjbnLQ8JIYdVw","https:\/\/www.linkedin.com\/company\/coralive-org\/"]},{"@type":"Person","@id":"https:\/\/www.coralive.org\/fr\/author\/rosybrown-swan-745870-hostingersite-com\/#author","url":"https:\/\/www.coralive.org\/fr\/author\/rosybrown-swan-745870-hostingersite-com\/","name":"Coralive","image":{"@type":"ImageObject","@id":"https:\/\/www.coralive.org\/fr\/updates-from-our-coral-research-in-theseychelles\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/6049c3d2ab23d730f1e9596931521d53e01945291f18c51f95f6af1c9ef8621b?s=96&d=mm&r=g","width":96,"height":96,"caption":"Coralive"}},{"@type":"WebPage","@id":"https:\/\/www.coralive.org\/fr\/updates-from-our-coral-research-in-theseychelles\/#webpage","url":"https:\/\/www.coralive.org\/fr\/updates-from-our-coral-research-in-theseychelles\/","name":"Updates from our Coral Research in the Seychelles - Coralive","description":"After months of meticulous work on Fregate Island, Seychelles, our 1 year-long coral restoration experiment comes to an end. Partnering on this project with Blancpain Ocean Commitment, we knew that Mineral Accretion Technology (MAT) would support the growth, health and survival of transplanted coral fragments.","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/www.coralive.org\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/www.coralive.org\/fr\/updates-from-our-coral-research-in-theseychelles\/#breadcrumblist"},"author":{"@id":"https:\/\/www.coralive.org\/fr\/author\/rosybrown-swan-745870-hostingersite-com\/#author"},"creator":{"@id":"https:\/\/www.coralive.org\/fr\/author\/rosybrown-swan-745870-hostingersite-com\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.coralive.org\/wp-content\/uploads\/2024\/05\/coral-research-in-the-seychelles-scaled.jpg","@id":"https:\/\/www.coralive.org\/fr\/updates-from-our-coral-research-in-theseychelles\/#mainImage","width":2560,"height":1920},"primaryImageOfPage":{"@id":"https:\/\/www.coralive.org\/fr\/updates-from-our-coral-research-in-theseychelles\/#mainImage"},"datePublished":"2022-05-15T12:01:14+01:00","dateModified":"2024-08-24T09:42:52+01:00"},{"@type":"WebSite","@id":"https:\/\/www.coralive.org\/fr\/#website","url":"https:\/\/www.coralive.org\/fr\/","name":"Coralive","description":"Powering the Future of Coral Restoration.","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/www.coralive.org\/fr\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"Coralive - Powering the Future of Coral Restoration.","og:type":"article","og:title":"Updates from our Coral Research in the Seychelles - Coralive","og:description":"After months of meticulous work on Fregate Island, Seychelles, our 1 year-long coral restoration experiment comes to an end. Partnering on this project with Blancpain Ocean Commitment, we knew that Mineral Accretion Technology (MAT) would support the growth, health and survival of transplanted coral fragments.","og:url":"https:\/\/www.coralive.org\/fr\/updates-from-our-coral-research-in-theseychelles\/","article:published_time":"2022-05-15T12:01:14+00:00","article:modified_time":"2024-08-24T08:42:52+00:00","article:publisher":"https:\/\/facebook.com\/coral.alive","twitter:card":"summary_large_image","twitter:title":"Updates from our Coral Research in the Seychelles - Coralive","twitter:description":"After months of meticulous work on Fregate Island, Seychelles, our 1 year-long coral restoration experiment comes to an end. Partnering on this project with Blancpain Ocean Commitment, we knew that Mineral Accretion Technology (MAT) would support the growth, health and survival of transplanted coral fragments."},"aioseo_meta_data":{"post_id":"69","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-05-23 12:27:45","updated":"2025-06-04 09:31:59","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.coralive.org\/fr\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.coralive.org\/fr\/category\/blog\/\" title=\"Blog\">Blog<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tUpdates from our Coral Research in the Seychelles\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.coralive.org\/fr"},{"label":"Blog","link":"https:\/\/www.coralive.org\/fr\/category\/blog\/"},{"label":"Updates from our Coral Research in the Seychelles","link":"https:\/\/www.coralive.org\/fr\/updates-from-our-coral-research-in-theseychelles\/"}],"_links":{"self":[{"href":"https:\/\/www.coralive.org\/fr\/wp-json\/wp\/v2\/posts\/69","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.coralive.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.coralive.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.coralive.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.coralive.org\/fr\/wp-json\/wp\/v2\/comments?post=69"}],"version-history":[{"count":2,"href":"https:\/\/www.coralive.org\/fr\/wp-json\/wp\/v2\/posts\/69\/revisions"}],"predecessor-version":[{"id":1381,"href":"https:\/\/www.coralive.org\/fr\/wp-json\/wp\/v2\/posts\/69\/revisions\/1381"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.coralive.org\/fr\/wp-json\/wp\/v2\/media\/63"}],"wp:attachment":[{"href":"https:\/\/www.coralive.org\/fr\/wp-json\/wp\/v2\/media?parent=69"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.coralive.org\/fr\/wp-json\/wp\/v2\/categories?post=69"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.coralive.org\/fr\/wp-json\/wp\/v2\/tags?post=69"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}